{"id":2789,"date":"2024-12-09T15:54:32","date_gmt":"2024-12-09T12:54:32","guid":{"rendered":"https:\/\/elafgroup.com\/?post_type=hotel&#038;p=2789"},"modified":"2024-12-09T15:56:19","modified_gmt":"2024-12-09T12:56:19","slug":"%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83","status":"publish","type":"hotel","link":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/","title":{"rendered":"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643"},"content":{"rendered":"\n<p>\u0627\u0643\u062a\u0634\u0641 \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 \u0627\u0644\u0648\u0627\u0642\u0639 \u0641\u064a \u0645\u0648\u0642\u0639 \u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a \u0641\u064a \u0642\u0644\u0628 \u0645\u062f\u064a\u0646\u0629 \u062c\u062f\u0629 \u0641\u064a \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629\u060c \u0627\u0644\u0630\u064a \u064a\u0642\u0639 \u0639\u0644\u0649 \u0628\u064f\u0639\u062f \u062f\u0642\u0627\u0626\u0642 \u00a0\u0645\u0646 \u0643\u0648\u0631\u0646\u064a\u0634 \u0627\u0644\u0628\u062d\u0631 \u0627\u0644\u0623\u062d\u0645\u0631 \u0627\u0644\u062e\u0644\u0627\u0628 \u0648\u0645\u0631\u0627\u0643\u0632 \u0627\u0644\u062a\u0633\u0648\u0642 \u0627\u0644\u0631\u0627\u0642\u064a\u0629. \u0627\u0633\u062a\u0645\u062a\u0639 \u0628\u0645\u0632\u064a\u062c \u0627\u0633\u062a\u062b\u0646\u0627\u0626\u064a \u064a\u062c\u0645\u0639 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0627\u0644\u063a\u0646\u064a\u0629 \u0648\u0627\u0644\u0645\u0639\u0627\u0644\u0645 \u0627\u0644\u0641\u0631\u064a\u062f\u0629 \u0644\u0645\u062f\u064a\u0646\u0629 \u062c\u062f\u0629 \u0645\u0639 \u0631\u0648\u062d \u0627\u0644\u0636\u064a\u0627\u0641\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629 \u0627\u0644\u0623\u0635\u064a\u0644\u0629 \u0641\u064a \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646\u060c\u062d\u064a\u062b \u064a\u062a\u0645 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0639\u0644\u0649 \u0643\u0644 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0628\u0627\u062a\u0642\u0627\u0646 \u0644\u062a\u062a\u062c\u0627\u0648\u0632 \u062a\u0648\u0642\u0639\u0627\u062a\u0643 \u0641\u064a \u0627\u0644\u0648\u062c\u0647\u0629 \u0627\u0644\u0645\u062b\u0627\u0644\u064a\u0629.<\/p>\n\n\n\n<p>\u064a\u062a\u0645\u062a\u0639 \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 \u0628\u0645\u0648\u0642\u0639 \u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a \u0639\u0644\u0649 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 \u0639\u0628\u062f \u0627\u0644\u0639\u0632\u064a\u0632\u060c \u0648\u0627\u0644\u0630\u064a \u064a\u0639\u062a\u0628\u0631 \u0645\u0646 \u0623\u0647\u0645 \u0627\u0644\u0637\u0631\u0642 \u0641\u064a \u0627\u0644\u0645\u0645\u0644\u0643\u0629\u060c \u0645\u0645\u0627 \u064a\u0639\u0632\u0632 \u062a\u062c\u0631\u0628\u0629 \u0625\u0642\u0627\u0645\u062a\u0643.<\/p>\n\n\n\n<p>\u064a\u0642\u0639 \u0647\u0630\u0627 \u0627\u0644\u0641\u0646\u062f\u0642 \u0628\u0627\u0644\u0642\u0631\u0628 \u0645\u0646 \u0627\u0644\u0648\u062c\u0647\u0627\u062a \u0627\u0644\u062a\u0631\u0641\u064a\u0647\u064a\u0629 \u0627\u0644\u0634\u0647\u064a\u0631\u0629 \u0645\u062b\u0644 \u0631\u062f\u0633\u064a \u0645\u0648\u0644 \u0648\u0643\u0648\u0631\u0646\u064a\u0634 \u062c\u062f\u0629\u060c \u0643\u0645\u0627 \u0648\u064a\u064f\u0633\u0647\u0651\u0644 \u0627\u0644\u0648\u0635\u0648\u0644 \u0627\u0644\u0649 \u0643\u0644 \u0645\u0646 \u0627\u0644\u0628\u0644\u062f\u060c \u0648\u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u062f\u064a\u0646\u0629\u060c \u0648\u0645\u0637\u0627\u0631 \u0627\u0644\u0645\u0644\u0643 \u0639\u0628\u062f \u0627\u0644\u0639\u0632\u064a\u0632.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center\">\n\n<a href=\"https:\/\/www.joudyanhotels.com\/ar\/red-sea-mall\" target=\"_blank\" style=\"font-size: 70% !important;\" class=\"btn button1\" rel=\"noopener\">\n\n<i class=\"icon me-1\">\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"14\" height=\"17\" viewBox=\"0 0 14 17\">\n<g id=\"Vector_Smart_Object\" data-name=\"Vector Smart Object\" transform=\"translate(-229.957 -100.897)\">\n<path id=\"Path_50\" data-name=\"Path 50\" d=\"M229.957,111h14v-3.393h-14Zm0,6.9h14V114.5h-14Zm0-17v3.393h14V100.9Z\" fill=\"#fff\"><\/path><\/g>\n<\/svg>\n<\/i>\nVisit Website\n<\/a>\n<\/p>\n","protected":false},"featured_media":2885,"template":"","class_list":["post-2789","hotel","type-hotel","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 - Elaf Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elafgroup.com\/ar\/hotel\/\u062c\u0648\u062f\u064a\u0627\u0646-\u0637\u0631\u064a\u0642-\u0627\u0644\u0645\u0644\u0643\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 - Elaf Group\" \/>\n<meta property=\"og:description\" content=\"\u0627\u0643\u062a\u0634\u0641 \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 \u0627\u0644\u0648\u0627\u0642\u0639 \u0641\u064a \u0645\u0648\u0642\u0639 \u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a \u0641\u064a \u0642\u0644\u0628 \u0645\u062f\u064a\u0646\u0629 \u062c\u062f\u0629 \u0641\u064a \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629\u060c \u0627\u0644\u0630\u064a \u064a\u0642\u0639 \u0639\u0644\u0649 \u0628\u064f\u0639\u062f \u062f\u0642\u0627\u0626\u0642 \u00a0\u0645\u0646 \u0643\u0648\u0631\u0646\u064a\u0634 \u0627\u0644\u0628\u062d\u0631 \u0627\u0644\u0623\u062d\u0645\u0631 \u0627\u0644\u062e\u0644\u0627\u0628 \u0648\u0645\u0631\u0627\u0643\u0632 \u0627\u0644\u062a\u0633\u0648\u0642 \u0627\u0644\u0631\u0627\u0642\u064a\u0629. \u0627\u0633\u062a\u0645\u062a\u0639 \u0628\u0645\u0632\u064a\u062c \u0627\u0633\u062a\u062b\u0646\u0627\u0626\u064a \u064a\u062c\u0645\u0639 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0627\u0644\u063a\u0646\u064a\u0629 \u0648\u0627\u0644\u0645\u0639\u0627\u0644\u0645 \u0627\u0644\u0641\u0631\u064a\u062f\u0629 \u0644\u0645\u062f\u064a\u0646\u0629 \u062c\u062f\u0629 \u0645\u0639 \u0631\u0648\u062d \u0627\u0644\u0636\u064a\u0627\u0641\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629 \u0627\u0644\u0623\u0635\u064a\u0644\u0629 \u0641\u064a \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646\u060c\u062d\u064a\u062b \u064a\u062a\u0645 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0639\u0644\u0649 \u0643\u0644 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0628\u0627\u062a\u0642\u0627\u0646 \u0644\u062a\u062a\u062c\u0627\u0648\u0632 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elafgroup.com\/ar\/hotel\/\u062c\u0648\u062f\u064a\u0627\u0646-\u0637\u0631\u064a\u0642-\u0627\u0644\u0645\u0644\u0643\/\" \/>\n<meta property=\"og:site_name\" content=\"Elaf Group\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T12:56:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elafgroup.com\/wp-content\/uploads\/2024\/07\/Photo-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u062f\u0642\u064a\u0642\u0629\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/\",\"url\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/\",\"name\":\"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 - Elaf Group\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elafgroup.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/elafgroup.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Photo-1.jpg\",\"datePublished\":\"2024-12-09T12:54:32+00:00\",\"dateModified\":\"2024-12-09T12:56:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/#primaryimage\",\"url\":\"https:\\\/\\\/elafgroup.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Photo-1.jpg\",\"contentUrl\":\"https:\\\/\\\/elafgroup.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/Photo-1.jpg\",\"width\":1500,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/hotel\\\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elafgroup.com\\\/ar\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elafgroup.com\\\/#website\",\"url\":\"https:\\\/\\\/elafgroup.com\\\/\",\"name\":\"Elaf Group\",\"description\":\"Arabian Hospitality\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/elafgroup.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 - Elaf Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elafgroup.com\/ar\/hotel\/\u062c\u0648\u062f\u064a\u0627\u0646-\u0637\u0631\u064a\u0642-\u0627\u0644\u0645\u0644\u0643\/","og_locale":"ar_AR","og_type":"article","og_title":"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 - Elaf Group","og_description":"\u0627\u0643\u062a\u0634\u0641 \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 \u0627\u0644\u0648\u0627\u0642\u0639 \u0641\u064a \u0645\u0648\u0642\u0639 \u0627\u0633\u062a\u0631\u0627\u062a\u064a\u062c\u064a \u0641\u064a \u0642\u0644\u0628 \u0645\u062f\u064a\u0646\u0629 \u062c\u062f\u0629 \u0641\u064a \u0627\u0644\u0645\u0645\u0644\u0643\u0629 \u0627\u0644\u0639\u0631\u0628\u064a\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629\u060c \u0627\u0644\u0630\u064a \u064a\u0642\u0639 \u0639\u0644\u0649 \u0628\u064f\u0639\u062f \u062f\u0642\u0627\u0626\u0642 \u00a0\u0645\u0646 \u0643\u0648\u0631\u0646\u064a\u0634 \u0627\u0644\u0628\u062d\u0631 \u0627\u0644\u0623\u062d\u0645\u0631 \u0627\u0644\u062e\u0644\u0627\u0628 \u0648\u0645\u0631\u0627\u0643\u0632 \u0627\u0644\u062a\u0633\u0648\u0642 \u0627\u0644\u0631\u0627\u0642\u064a\u0629. \u0627\u0633\u062a\u0645\u062a\u0639 \u0628\u0645\u0632\u064a\u062c \u0627\u0633\u062a\u062b\u0646\u0627\u0626\u064a \u064a\u062c\u0645\u0639 \u0627\u0644\u062b\u0642\u0627\u0641\u0629 \u0627\u0644\u063a\u0646\u064a\u0629 \u0648\u0627\u0644\u0645\u0639\u0627\u0644\u0645 \u0627\u0644\u0641\u0631\u064a\u062f\u0629 \u0644\u0645\u062f\u064a\u0646\u0629 \u062c\u062f\u0629 \u0645\u0639 \u0631\u0648\u062d \u0627\u0644\u0636\u064a\u0627\u0641\u0629 \u0627\u0644\u0633\u0639\u0648\u062f\u064a\u0629 \u0627\u0644\u0623\u0635\u064a\u0644\u0629 \u0641\u064a \u0641\u0646\u062f\u0642 \u062c\u0648\u062f\u064a\u0627\u0646\u060c\u062d\u064a\u062b \u064a\u062a\u0645 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0639\u0644\u0649 \u0643\u0644 \u0627\u0644\u062a\u0641\u0627\u0635\u064a\u0644 \u0628\u0627\u062a\u0642\u0627\u0646 \u0644\u062a\u062a\u062c\u0627\u0648\u0632 [&hellip;]","og_url":"https:\/\/elafgroup.com\/ar\/hotel\/\u062c\u0648\u062f\u064a\u0627\u0646-\u0637\u0631\u064a\u0642-\u0627\u0644\u0645\u0644\u0643\/","og_site_name":"Elaf Group","article_modified_time":"2024-12-09T12:56:19+00:00","og_image":[{"width":1500,"height":1125,"url":"https:\/\/elafgroup.com\/wp-content\/uploads\/2024\/07\/Photo-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u0648\u0642\u062a \u0627\u0644\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u064f\u0642\u062f\u0651\u0631":"1 \u062f\u0642\u064a\u0642\u0629"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/","url":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/","name":"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643 - Elaf Group","isPartOf":{"@id":"https:\/\/elafgroup.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/#primaryimage"},"image":{"@id":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/#primaryimage"},"thumbnailUrl":"https:\/\/elafgroup.com\/wp-content\/uploads\/2024\/07\/Photo-1.jpg","datePublished":"2024-12-09T12:54:32+00:00","dateModified":"2024-12-09T12:56:19+00:00","breadcrumb":{"@id":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/#primaryimage","url":"https:\/\/elafgroup.com\/wp-content\/uploads\/2024\/07\/Photo-1.jpg","contentUrl":"https:\/\/elafgroup.com\/wp-content\/uploads\/2024\/07\/Photo-1.jpg","width":1500,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/elafgroup.com\/ar\/hotel\/%d8%ac%d9%88%d8%af%d9%8a%d8%a7%d9%86-%d8%b7%d8%b1%d9%8a%d9%82-%d8%a7%d9%84%d9%85%d9%84%d9%83\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elafgroup.com\/ar\/"},{"@type":"ListItem","position":2,"name":"\u062c\u0648\u062f\u064a\u0627\u0646 \u0637\u0631\u064a\u0642 \u0627\u0644\u0645\u0644\u0643"}]},{"@type":"WebSite","@id":"https:\/\/elafgroup.com\/#website","url":"https:\/\/elafgroup.com\/","name":"Elaf Group","description":"Arabian Hospitality","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elafgroup.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"}]}},"_links":{"self":[{"href":"https:\/\/elafgroup.com\/ar\/wp-json\/wp\/v2\/hotel\/2789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elafgroup.com\/ar\/wp-json\/wp\/v2\/hotel"}],"about":[{"href":"https:\/\/elafgroup.com\/ar\/wp-json\/wp\/v2\/types\/hotel"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elafgroup.com\/ar\/wp-json\/wp\/v2\/media\/2885"}],"wp:attachment":[{"href":"https:\/\/elafgroup.com\/ar\/wp-json\/wp\/v2\/media?parent=2789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}